{"id":1475,"date":"2018-09-12T11:01:15","date_gmt":"2018-09-12T11:01:15","guid":{"rendered":"http:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/"},"modified":"2018-09-12T11:01:15","modified_gmt":"2018-09-12T11:01:15","slug":"loja-usada-para-venda-cascais-carcavelos-e-parede-2","status":"publish","type":"post","link":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/","title":{"rendered":"Loja, usada, para venda, Cascais &#8211; Carcavelos e Parede"},"content":{"rendered":"<p>(ref.: _10142 &#8211; imo2007 lisboa) **im&oacute;vel de banco. loja na parede. im&oacute;vel localizado na consolidad&#8230;Loja, usada, para venda, Cascais &#8211; Carcavelos e&amp;nbsp;&#8230;<br \/><a href=\"http:\/\/www.vivalocal.pt\/comercial-sala-loja\/cascais\/loja--usada--para-venda--cascais---carcavelos-e-parede\/190768770\" target=\"_blank\" title=\"Loja, usada, para venda, Cascais - Carcavelos e Parede\"> View full source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(ref.: _10142 &#8211; imo2007 lisboa) **im&oacute;vel de banco. loja na parede. im&oacute;vel localizado na consolidad&#8230;Loja, [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[59],"class_list":["post-1475","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-vivalocal"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News<\/title>\n<meta name=\"description\" content=\"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News\" \/>\n<meta property=\"og:description\" content=\"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News\" \/>\n<meta property=\"og:url\" content=\"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Carcavelos News\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-12T11:01:15+00:00\" \/>\n<meta name=\"author\" content=\"Carcavelos News\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carcavelos News\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/\"},\"author\":{\"name\":\"Carcavelos News\",\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/56195b46cace52b14c9228c7b35fedba\"},\"headline\":\"Loja, usada, para venda, Cascais &#8211; Carcavelos e Parede\",\"datePublished\":\"2018-09-12T11:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/\"},\"wordCount\":40,\"publisher\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/56195b46cace52b14c9228c7b35fedba\"},\"keywords\":[\"vivalocal\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/\",\"url\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/\",\"name\":\"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#website\"},\"datePublished\":\"2018-09-12T11:01:15+00:00\",\"description\":\"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/2018\\\/09\\\/12\\\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Loja, usada, para venda, Cascais &#8211; Carcavelos e Parede\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/\",\"name\":\"Carcavelos News\",\"description\":\"Daily news about Carcavelos (Cascais, Portugal) - fresh news, every day\",\"publisher\":{\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/56195b46cace52b14c9228c7b35fedba\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/#\\\/schema\\\/person\\\/56195b46cace52b14c9228c7b35fedba\",\"name\":\"Carcavelos News\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g\",\"caption\":\"Carcavelos News\"},\"logo\":{\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g\"},\"sameAs\":[\"http:\\\/\\\/carcavelos.4800bps.com\\\/blog\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","description":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/","og_locale":"en_US","og_type":"article","og_title":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","og_description":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","og_url":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/","og_site_name":"Carcavelos News","article_published_time":"2018-09-12T11:01:15+00:00","author":"Carcavelos News","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Carcavelos News"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/#article","isPartOf":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/"},"author":{"name":"Carcavelos News","@id":"https:\/\/carcavelos.4800bps.com\/blog\/#\/schema\/person\/56195b46cace52b14c9228c7b35fedba"},"headline":"Loja, usada, para venda, Cascais &#8211; Carcavelos e Parede","datePublished":"2018-09-12T11:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/"},"wordCount":40,"publisher":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/#\/schema\/person\/56195b46cace52b14c9228c7b35fedba"},"keywords":["vivalocal"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/","url":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/","name":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","isPartOf":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/#website"},"datePublished":"2018-09-12T11:01:15+00:00","description":"Loja, usada, para venda, Cascais - Carcavelos e Parede - Carcavelos News","breadcrumb":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/carcavelos.4800bps.com\/blog\/2018\/09\/12\/loja-usada-para-venda-cascais-carcavelos-e-parede-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/carcavelos.4800bps.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Loja, usada, para venda, Cascais &#8211; Carcavelos e Parede"}]},{"@type":"WebSite","@id":"https:\/\/carcavelos.4800bps.com\/blog\/#website","url":"https:\/\/carcavelos.4800bps.com\/blog\/","name":"Carcavelos News","description":"Daily news about Carcavelos (Cascais, Portugal) - fresh news, every day","publisher":{"@id":"https:\/\/carcavelos.4800bps.com\/blog\/#\/schema\/person\/56195b46cace52b14c9228c7b35fedba"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/carcavelos.4800bps.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/carcavelos.4800bps.com\/blog\/#\/schema\/person\/56195b46cace52b14c9228c7b35fedba","name":"Carcavelos News","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g","caption":"Carcavelos News"},"logo":{"@id":"https:\/\/secure.gravatar.com\/avatar\/8b3ed80b26ccd06fd0b22ebe5ff621d7f8bb6df2742f40bd51bfc77ad1868bdc?s=96&d=mm&r=g"},"sameAs":["http:\/\/carcavelos.4800bps.com\/blog\/"]}]}},"_links":{"self":[{"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/1475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/comments?post=1475"}],"version-history":[{"count":0,"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/posts\/1475\/revisions"}],"wp:attachment":[{"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/media?parent=1475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/categories?post=1475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/carcavelos.4800bps.com\/blog\/wp-json\/wp\/v2\/tags?post=1475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}